{"id":27786,"date":"2026-05-17T22:17:42","date_gmt":"2026-05-17T22:17:42","guid":{"rendered":"https:\/\/lekysha.com\/shop\/bioglide-lubricante-aceite-de-masaje-organico-125-ml\/"},"modified":"2026-07-15T08:29:27","modified_gmt":"2026-07-15T08:29:27","slug":"bioglide-lubricante-aceite-de-masaje-organico-125-ml","status":"publish","type":"product","link":"https:\/\/lekysha.com\/en\/shop\/bioglide-lubricante-aceite-de-masaje-organico-125-ml\/","title":{"rendered":"BIOGLIDE &#8211; \u00d3LEO DE MASSAGEM E LUBRIFICANTE ORG\u00c2NICO 125 ML"},"content":{"rendered":"<p>Original BIOglide ? o primeiro &oacute;leo de massagem e lubrificante combinado 100% org&acirc;nico do mundo.<\/p>\n<p>O &oacute;leo medicinal aumenta visivelmente a lubrifica&ccedil;&atilde;o durante a rela&ccedil;&atilde;o sexual e ajuda a reduzir o desconforto &iacute;ntimo. Como um &oacute;leo de massagem de corpo inteiro, mima a pele com um cuidado profundamente hidratante.<\/p>\n<ul>\n<li>Livre de parabenos, fragr&acirc;ncias sint&eacute;ticas e, portanto, totalmente amigo da pele e adequado para &aacute;reas &iacute;ntimas (mucosa).<\/li>\n<li>Perfeito para uso vaginal, anal ou oral.<\/li>\n<li>Aplica&ccedil;&atilde;o: Basta aplicar uma pequena quantidade na &aacute;rea desejada<\/li>\n<li>N&atilde;o &eacute; compat&iacute;vel com preservativos de l&aacute;tex.<\/li>\n<li>O primeiro lubrificante e &oacute;leo de massagem combinado 100% org&acirc;nico do mundo<\/li>\n<li>cuidado hidratante<\/li>\n<li>Tamb&eacute;m adequado para uso de corpo inteiro<\/li>\n<li>Sem cheiro e sem sabor para todos que valorizam a naturalidade auxiliam suavemente a sexualidade<\/li>\n<li>LIVRE de conservantes sint&eacute;ticos (como parabenos)<\/li>\n<li>LIVRE de fragr&acirc;ncias sint&eacute;ticas<\/li>\n<li>100% natural + qualidade alimentar vegana dermatologicamente + produto m&eacute;dico clinicamente testado com pH otimizado (para Intimate-Balance)<\/li>\n<li>Also suitable for oral pleasure.<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>PACKAGING AVAILABLE IN: \/es\/pt\/de\/<\/p>","protected":false},"featured_media":27787,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[]},"product_brand":[251],"product_cat":[879,887,947,881,907],"product_tag":[],"class_list":["post-27786","product","type-product","status-publish","has-post-thumbnail","product_brand-joydivision-bioglide","product_cat-essenciais-intimos","product_cat-lubrificantes","product_cat-lubrificantes-organicos","product_cat-massagem-sensual","product_cat-oleos-massagem-neutros","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product\/27786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/comments?post=27786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/media\/27787"}],"wp:attachment":[{"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/media?parent=27786"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product_brand?post=27786"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product_cat?post=27786"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product_tag?post=27786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}