{"id":48716,"date":"2026-05-19T03:39:22","date_gmt":"2026-05-19T03:39:22","guid":{"rendered":"https:\/\/lekysha.com\/shop\/mister-size-lubrificante-premium-100-ml\/"},"modified":"2026-06-04T09:19:19","modified_gmt":"2026-06-04T09:19:19","slug":"mister-size-lubrificante-premium-100-ml","status":"publish","type":"product","link":"https:\/\/lekysha.com\/en\/shop\/mister-size-lubrificante-premium-100-ml\/","title":{"rendered":"MISTER SIZE &#8211; LUBRIFICANTE PREMIUM 100 ML"},"content":{"rendered":"<p>Lubrificante MISTER SIZE Descubra agora: o lubrificante \u00e0 base de \u00e1gua Mister Size \u00e9 a combina\u00e7\u00e3o perfeita para o preservativo, assim como o preservativo \u00e9 para voc\u00ea.<\/p>\n<p> <u><strong>Highlights:<\/strong><\/u><\/p>\n<ul>\n<li> F\u00f3rmula \u00e0 base de \u00e1gua<\/li>\n<li> Lubrifica\u00e7\u00e3o de longa dura\u00e7\u00e3o<\/li>\n<\/ul>\n<p> <u><strong>Why use lubricant?<\/strong><\/u><br \/> Porque \u00e9 divertido O carro funciona melhor quando \u00e9 lubrificado recentemente. O mesmo vale para o lubrificante na cama! Cada movimento se torna<br \/> uma experi\u00eancia sedosa e excitante. Conven\u00e7a-se do efeito duradouro do lubrificante MISTER SIZE e desfrute de horas infinitas de paix\u00e3o.<br \/> Gra\u00e7as \u00e0 sua f\u00f3rmula \u00e0 base de \u00e1gua, o lubrificante tamb\u00e9m \u00e9 adequado para peles sens\u00edveis e pode ser simplesmente enxaguado com \u00e1gua normal ap\u00f3s o uso.<br \/> O gel lubrificante MISTER SIZE cont\u00e9m apenas ingredientes de alta qualidade para compatibilidade ideal com a pele. O gel lubrificante MISTER SIZE \u00e9 dermatologicamente testado, sem gordura, incolor, inodoro e ins\u00edpido.<\/p>\n<p> Gel lubrificante MISTER SIZE \u00c9 um produto vers\u00e1til que pode ser usado com brinquedos e preservativos e n\u00e3o deixa manchas permanentes nos tecidos.<\/p>\n<p> O tubo de 100 ml tem o tamanho perfeito para uso ocasional ou regular e \u00e9 visualmente convincente devido ao seu design moderno de embalagem. Assim como cremes para as m\u00e3os, a tampa pode ser aberta num piscar de olhos atrav\u00e9s do fecho flip-top, caso voc\u00ea precise de uma recarga r\u00e1pida &quot;enquanto isso&quot;.<br \/> A consist\u00eancia cristalina espalha-se facilmente nas \u00e1reas desejadas e proporciona hidrata\u00e7\u00e3o intensa para a melhor experi\u00eancia sensorial poss\u00edvel.<\/p>\n<p> <strong>Aplica\u00e7\u00e3o e armazenamento<\/strong><br \/> Basta aplicar uma pequena quantidade do gel lubrificante MISTER SIZE na parte desejada do corpo e mergulhar na fant\u00e1stica aventura da umidade. Repita a opera\u00e7\u00e3o conforme necess\u00e1rio. Mantenha fora do alcance de crian\u00e7as. Recomendamos armazen\u00e1-lo em um local fresco e escuro.<\/p>\n<p> <strong>Full list of ingredients:<\/strong><br \/> \u00c1gua, Glicerina, Hidroxietilcelulose, \u00c1cido C\u00edtrico, Benzoato de S\u00f3dio, Sorbato de Pot\u00e1ssio, Pentilenoglicol, Sorbitol, Lactato de S\u00f3dio, Ureia, \u00c1cido L\u00e1tico, Serina, Hidr\u00f3xido de S\u00f3dio, Cloreto de S\u00f3dio, Alanto\u00edna<\/p>","protected":false},"excerpt":{"rendered":"<p>MISTER SIZE &#8211; LUBRIFICANTE PREMIUM 100 ML<\/p>","protected":false},"featured_media":48717,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[]},"product_brand":[1721],"product_cat":[893],"product_tag":[],"class_list":["post-48716","product","type-product","status-publish","has-post-thumbnail","product_brand-mister-size","product_cat-essenciais","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product\/48716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/comments?post=48716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/media\/48717"}],"wp:attachment":[{"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/media?parent=48716"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product_brand?post=48716"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product_cat?post=48716"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lekysha.com\/en\/wp-json\/wp\/v2\/product_tag?post=48716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}